{"id":11,"count":6,"description":"","link":"https:\/\/urmepeplay.ro\/en\/category\/media\/","name":"Media","slug":"media","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Media Archives - Urme pe play<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/urmepeplay.ro\/en\/category\/media\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Media Archives - Urme pe play\" \/>\n<meta property=\"og:url\" content=\"https:\/\/urmepeplay.ro\/en\/category\/media\/\" \/>\n<meta property=\"og:site_name\" content=\"Urme pe play\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/category\\\/media\\\/\",\"url\":\"https:\\\/\\\/urmepeplay.ro\\\/category\\\/media\\\/\",\"name\":\"Media Archives - Urme pe play\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/category\\\/media\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/category\\\/media\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/urmepeplay.ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Media\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/\",\"name\":\"Urme pe play\",\"description\":\"Urme pe play\",\"publisher\":{\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/#organization\",\"name\":\"Urme pe play\",\"url\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/urmepeplay.ro\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/new-logo-big.svg\",\"contentUrl\":\"https:\\\/\\\/urmepeplay.ro\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/new-logo-big.svg\",\"width\":320,\"height\":82,\"caption\":\"Urme pe play\"},\"image\":{\"@id\":\"https:\\\/\\\/urmepeplay.ro\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/@UrmePePlay\\\/\",\"https:\\\/\\\/www.instagram.com\\\/urmepeplay\",\"https:\\\/\\\/www.youtube.com\\\/@UrmepePlay\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Media Archives - Urme pe play","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/urmepeplay.ro\/en\/category\/media\/","og_locale":"en_US","og_type":"article","og_title":"Media Archives - Urme pe play","og_url":"https:\/\/urmepeplay.ro\/en\/category\/media\/","og_site_name":"Urme pe play","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/urmepeplay.ro\/category\/media\/","url":"https:\/\/urmepeplay.ro\/category\/media\/","name":"Media Archives - Urme pe play","isPartOf":{"@id":"https:\/\/urmepeplay.ro\/en\/#website"},"breadcrumb":{"@id":"https:\/\/urmepeplay.ro\/category\/media\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/urmepeplay.ro\/category\/media\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/urmepeplay.ro\/"},{"@type":"ListItem","position":2,"name":"Media"}]},{"@type":"WebSite","@id":"https:\/\/urmepeplay.ro\/en\/#website","url":"https:\/\/urmepeplay.ro\/en\/","name":"Urme pe play","description":"Urme pe play","publisher":{"@id":"https:\/\/urmepeplay.ro\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/urmepeplay.ro\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/urmepeplay.ro\/en\/#organization","name":"Urme pe play","url":"https:\/\/urmepeplay.ro\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/urmepeplay.ro\/en\/#\/schema\/logo\/image\/","url":"https:\/\/urmepeplay.ro\/wp-content\/uploads\/2020\/02\/new-logo-big.svg","contentUrl":"https:\/\/urmepeplay.ro\/wp-content\/uploads\/2020\/02\/new-logo-big.svg","width":320,"height":82,"caption":"Urme pe play"},"image":{"@id":"https:\/\/urmepeplay.ro\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/@UrmePePlay\/","https:\/\/www.instagram.com\/urmepeplay","https:\/\/www.youtube.com\/@UrmepePlay"]}]}},"_links":{"self":[{"href":"https:\/\/urmepeplay.ro\/en\/wp-json\/wp\/v2\/categories\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urmepeplay.ro\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/urmepeplay.ro\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/urmepeplay.ro\/en\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}